{"id":2939,"date":"2022-10-26T13:18:35","date_gmt":"2022-10-26T13:18:35","guid":{"rendered":"https:\/\/ide-tech.com\/?post_type=project&#038;p=2939"},"modified":"2023-12-26T14:19:02","modified_gmt":"2023-12-26T14:19:02","slug":"planta-desalinizadora-de-ashkelon","status":"publish","type":"project","link":"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/","title":{"rendered":"Planta desalinizadora de Ashkelon (Israel)"},"content":{"rendered":"<p>La planta de desalinizaci\u00f3n m\u00e1s grande del hemisferio occidental y un cambio de juego completo para la desalinizaci\u00f3n en los EE. UU.<\/p>\n","protected":false},"author":28,"featured_media":0,"parent":0,"menu_order":20,"template":"","projectlocation":[70],"projecttype":[181,180,179],"projecttech":[85],"class_list":["post-2939","project","type-project","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Planta desalinizadora de Ashkelon (Israel) | IDE Tech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planta desalinizadora de Ashkelon (Israel) | IDE Tech\" \/>\n<meta property=\"og:description\" content=\"La planta de desalinizaci\u00f3n m\u00e1s grande del hemisferio occidental y un cambio de juego completo para la desalinizaci\u00f3n en los EE. UU.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/\" \/>\n<meta property=\"og:site_name\" content=\"IDE Tech\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-26T14:19:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/project\\\/planta-desalinizadora-de-ashkelon\\\/\",\"url\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/project\\\/planta-desalinizadora-de-ashkelon\\\/\",\"name\":\"Planta desalinizadora de Ashkelon (Israel) | IDE Tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ide-tech.com\\\/en\\\/#website\"},\"datePublished\":\"2022-10-26T13:18:35+00:00\",\"dateModified\":\"2023-12-26T14:19:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/project\\\/planta-desalinizadora-de-ashkelon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ide-tech.com\\\/es\\\/project\\\/planta-desalinizadora-de-ashkelon\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/project\\\/planta-desalinizadora-de-ashkelon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/hogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Planta desalinizadora de Ashkelon (Israel)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ide-tech.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ide-tech.com\\\/en\\\/\",\"name\":\"IDE Tech\",\"description\":\"Your Water Partner\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ide-tech.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planta desalinizadora de Ashkelon (Israel) | IDE Tech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/","og_locale":"es_ES","og_type":"article","og_title":"Planta desalinizadora de Ashkelon (Israel) | IDE Tech","og_description":"La planta de desalinizaci\u00f3n m\u00e1s grande del hemisferio occidental y un cambio de juego completo para la desalinizaci\u00f3n en los EE. UU.","og_url":"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/","og_site_name":"IDE Tech","article_modified_time":"2023-12-26T14:19:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/","url":"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/","name":"Planta desalinizadora de Ashkelon (Israel) | IDE Tech","isPartOf":{"@id":"https:\/\/ide-tech.com\/en\/#website"},"datePublished":"2022-10-26T13:18:35+00:00","dateModified":"2023-12-26T14:19:02+00:00","breadcrumb":{"@id":"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ide-tech.com\/es\/project\/planta-desalinizadora-de-ashkelon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ide-tech.com\/es\/hogar\/"},{"@type":"ListItem","position":2,"name":"Planta desalinizadora de Ashkelon (Israel)"}]},{"@type":"WebSite","@id":"https:\/\/ide-tech.com\/en\/#website","url":"https:\/\/ide-tech.com\/en\/","name":"IDE Tech","description":"Your Water Partner","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ide-tech.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/project\/2939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/users\/28"}],"version-history":[{"count":4,"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/project\/2939\/revisions"}],"predecessor-version":[{"id":8076,"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/project\/2939\/revisions\/8076"}],"wp:attachment":[{"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/media?parent=2939"}],"wp:term":[{"taxonomy":"projectlocation","embeddable":true,"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/projectlocation?post=2939"},{"taxonomy":"projecttype","embeddable":true,"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/projecttype?post=2939"},{"taxonomy":"projecttech","embeddable":true,"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/projecttech?post=2939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}