{"id":10512,"date":"2025-10-26T13:09:07","date_gmt":"2025-10-26T13:09:07","guid":{"rendered":"https:\/\/staging.ide-tech.com\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/"},"modified":"2025-10-26T13:09:07","modified_gmt":"2025-10-26T13:09:07","slug":"ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion","status":"publish","type":"newsandevents","link":"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/","title":{"rendered":"IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n"},"content":{"rendered":"<p>IDE Technologies se enorgullece de anunciar que ha sido galardonada con el <strong>Premio de Oro en la categor\u00eda de Innovaci\u00f3n en Tecnolog\u00eda de Gesti\u00f3n del Agua<\/strong> en la 17.\u00aa edici\u00f3n de los <strong>Annual 2025 Globee\u00ae Awards for Innovation<\/strong>, tambi\u00e9n conocidos como Golden Bridge Awards\u00ae. Este prestigioso programa de premios reconoce las iniciativas, los productos, los servicios y las personas m\u00e1s innovadores del mundo que impulsan un cambio significativo.<\/p>\n<p>IDE recibi\u00f3 el premio por su soluci\u00f3n integral y sostenible para el centro de desalaci\u00f3n y energ\u00eda. Este innovador sistema combina tecnolog\u00edas de vanguardia, bombas de alta presi\u00f3n accionadas por vapor, sistemas energ\u00e9ticamente eficientes y captura de carbono integrada en una soluci\u00f3n unificada de gesti\u00f3n del agua. La soluci\u00f3n se encuentra actualmente implementada en la desaladora por \u00f3smosis inversa (SWRO) de agua de mar Sorek 2: Be\u2019er Miriam, lo que ha reducido significativamente su huella medioambiental y ha mejorado la eficiencia operativa.<\/p>\n<p>\u00abDurante m\u00e1s de sesenta a\u00f1os, IDE ha proporcionado soluciones innovadoras y sostenibles para el agua que abordan los retos globales al tiempo que defienden la gesti\u00f3n medioambiental\u00bb, afirm\u00f3 Nilly Maik, directora de Mercadotecnia de IDE. \u00abNos sentimos honrados de que los prestigiosos jueces de los premios Globee\u00ae hayan reconocido el valor de nuestra soluci\u00f3n unificada de gesti\u00f3n del agua. Su exitosa implementaci\u00f3n en Sorek 2: Be\u2019er Miriam demuestra el potencial transformador de este sistema, y esperamos ampliar su impacto en 2026 y m\u00e1s all\u00e1\u00bb.<\/p>\n<p>El impacto de esta innovaci\u00f3n en la planta Sorek 2: Be\u2019er Miriam ha sido significativo, estableciendo un nuevo punto de referencia para la desalaci\u00f3n energ\u00e9ticamente eficiente. Por ejemplo, el sistema de transmisi\u00f3n directa de la planta contribuye a reducir hasta un 10 % el consumo de energ\u00eda espec\u00edfica (SE) y, en combinaci\u00f3n con su sistema completo de captura, utilizaci\u00f3n y almacenamiento de carbono (CCUS), reduce sus emisiones de carbono en un 30 % en comparaci\u00f3n con las desaladoras tradicionales. Esta tecnolog\u00eda ha contribuido a que Sorek 2: Be\u2019er Miriam se convierta en una de las plantas SWRO m\u00e1s grandes y avanzadas del mundo, con una impresionante producci\u00f3n de 672 000 m3\/d\u00eda.<\/p>\n<p>\u00abLos ganadores de los 2025 Globee\u00ae Awards for Innovation encarnan lo que significa desafiar el statu quo\u00bb, afirm\u00f3 San Madan, presidente de los Globee\u00ae Awards. \u00abSus ideas audaces y soluciones innovadoras no solo est\u00e1n transformando las industrias, sino que tambi\u00e9n est\u00e1n dando forma al futuro. Aplaudimos su valent\u00eda, creatividad y compromiso para generar un impacto real en el mundo\u00bb.<\/p>\n<p>Consulte aqu\u00ed la lista completa de ganadores: <a href=\"https:\/\/globeeawards.com\/innovation\/winners\/\">https:\/\/globeeawards.com\/innovation\/winners\/<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":38,"template":"","newseventcat":[96],"class_list":["post-10512","newsandevents","type-newsandevents","status-publish","hentry","newseventcat-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n | IDE Tech<\/title>\n<meta name=\"description\" content=\"IDE es pionera en la desalaci\u00f3n sostenible con Sorek 2 y Be\u2019er Miriam, ofreciendo soluciones energ\u00e9ticamente eficientes para las necesidades h\u00eddricas del futuro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n | IDE Tech\" \/>\n<meta property=\"og:description\" content=\"IDE es pionera en la desalaci\u00f3n sostenible con Sorek 2 y Be\u2019er Miriam, ofreciendo soluciones energ\u00e9ticamente eficientes para las necesidades h\u00eddricas del futuro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/\" \/>\n<meta property=\"og:site_name\" content=\"IDE Tech\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\\\/\",\"url\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\\\/\",\"name\":\"IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n | IDE Tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ide-tech.com\\\/en\\\/#website\"},\"datePublished\":\"2025-10-26T13:09:07+00:00\",\"description\":\"IDE es pionera en la desalaci\u00f3n sostenible con Sorek 2 y Be\u2019er Miriam, ofreciendo soluciones energ\u00e9ticamente eficientes para las necesidades h\u00eddricas del futuro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ide-tech.com\\\/es\\\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ide-tech.com\\\/es\\\/hogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ide-tech.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ide-tech.com\\\/en\\\/\",\"name\":\"IDE Tech\",\"description\":\"Your Water Partner\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ide-tech.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n | IDE Tech","description":"IDE es pionera en la desalaci\u00f3n sostenible con Sorek 2 y Be\u2019er Miriam, ofreciendo soluciones energ\u00e9ticamente eficientes para las necesidades h\u00eddricas del futuro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/","og_locale":"es_ES","og_type":"article","og_title":"IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n | IDE Tech","og_description":"IDE es pionera en la desalaci\u00f3n sostenible con Sorek 2 y Be\u2019er Miriam, ofreciendo soluciones energ\u00e9ticamente eficientes para las necesidades h\u00eddricas del futuro.","og_url":"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/","og_site_name":"IDE Tech","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/","url":"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/","name":"IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n | IDE Tech","isPartOf":{"@id":"https:\/\/ide-tech.com\/en\/#website"},"datePublished":"2025-10-26T13:09:07+00:00","description":"IDE es pionera en la desalaci\u00f3n sostenible con Sorek 2 y Be\u2019er Miriam, ofreciendo soluciones energ\u00e9ticamente eficientes para las necesidades h\u00eddricas del futuro.","breadcrumb":{"@id":"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ide-tech.com\/es\/ide-technologies-gana-el-oro-en-los-premios-globee-2025-a-la-innovacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ide-tech.com\/es\/hogar\/"},{"@type":"ListItem","position":2,"name":"IDE Technologies gana el oro en los Premios Globee\u00ae 2025 a la Innovaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/ide-tech.com\/en\/#website","url":"https:\/\/ide-tech.com\/en\/","name":"IDE Tech","description":"Your Water Partner","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ide-tech.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/newsandevents\/10512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/newsandevents"}],"about":[{"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/types\/newsandevents"}],"wp:attachment":[{"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/media?parent=10512"}],"wp:term":[{"taxonomy":"newseventcat","embeddable":true,"href":"https:\/\/ide-tech.com\/es\/wp-json\/wp\/v2\/newseventcat?post=10512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}